{"id":145244,"date":"2022-11-19T08:02:51","date_gmt":"2022-11-19T08:02:51","guid":{"rendered":"https:\/\/www.testing.devjibble.net\/help\/analyzing-hours-with-the-tracked-time-report\/"},"modified":"2026-03-30T23:45:36","modified_gmt":"2026-03-30T22:45:36","slug":"analisando-horas-relatorio-horas-registradas","status":"publish","type":"help","link":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas","title":{"rendered":"Analisando horas com o Relat\u00f3rio de Horas Registradas"},"content":{"rendered":"<p class=\"no-margin\">O Relat\u00f3rio de Horas Registradas pode ser usado para analisar horas e obter insights por meio de gr\u00e1ficos simples, com base em como sua equipe est\u00e1 registrando o tempo em atividades, projetos e clientes.<\/p>\n<p class=\"no-margin\">Ele pode ser encontrado na se\u00e7\u00e3o de Relat\u00f3rios do seu aplicativo web, dispon\u00edvel para propriet\u00e1rios e administradores.<\/p>\n<p class=\"no-margin\"><strong>Este artigo aborda:<\/strong><\/p>\n<ul>\n<li class=\"no-margin\"><a class=\"intercom-content-link\" href=\"#como-usar-relatorio-horas-registradas\" target=\"_self\" rel=\"nofollow noopener noreferrer\">Como usar o Relat\u00f3rio de Horas Registradas<\/a><\/li>\n<li class=\"no-margin\"><a class=\"intercom-content-link\" href=\"#exportando-relatorio-horas-registradas\" target=\"_self\" rel=\"nofollow noopener noreferrer\">Exportando o Relat\u00f3rio de Horas Registradas<\/a><\/li>\n<\/ul>\n<p class=\"no-margin\"><em><strong>Nota: <\/strong>Este relat\u00f3rio gera dados apenas com base nas <b> horas registradas nas folhas de ponto.<\/b> Horas ajustadas manualmente para a folha de pagamento n\u00e3o est\u00e3o dispon\u00edveis neste relat\u00f3rio.<\/em><\/p>\n<hr \/>\n<h2 id=\"como-usar-relatorio-horas-registradas\" data-post-processed=\"true\">Como usar o Relat\u00f3rio de Horas Registradas<\/h2>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"size-full wp-image-164064 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png\" alt=\"tracked time report\" width=\"1792\" height=\"1047\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png 1792w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR-300x175.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR-768x449.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR-1536x897.png 1536w\" sizes=\"(max-width: 1792px) 100vw, 1792px\" \/><\/div>\n<p class=\"no-margin\">Se voc\u00ea precisar gerar um relat\u00f3rio das horas registradas pela sua equipe em suas atividades\/projetos\/clientes ou gerar faturas para seus clientes, voc\u00ea pode usar o Relat\u00f3rio de Horas Registradas.<\/p>\n<h3 id=\"filtros-categorias\" data-post-processed=\"true\">Filtros e categorias<\/h3>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"size-full wp-image-164075 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-filters-PTBR.png\" alt=\"tracked time report filters\" width=\"1705\" height=\"652\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-filters-PTBR.png 1705w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-filters-PTBR-300x115.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-filters-PTBR-768x294.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-filters-PTBR-1536x587.png 1536w\" sizes=\"(max-width: 1705px) 100vw, 1705px\" \/><\/div>\n<p class=\"no-margin\">Voc\u00ea pode usar as categorias para ajustar o intervalo de datas e as configura\u00e7\u00f5es de grupo\/subgrupo, o que atualizar\u00e1 os dados no resumo da tabela abaixo para refletir o novo conte\u00fado do relat\u00f3rio.<\/p>\n<ol>\n<li>\n<p class=\"no-margin\">Selecione os filtros de <b>data<\/b> para escolher por semana, m\u00eas ou personalizado.<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Selecione se deseja agrupar por <b>Data, Membro, Atividade, Projeto ou Cliente.<\/b><\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Selecione seu <b>subgrupo.<br \/>\n<\/b><\/p>\n<ol style=\"list-style-type: lower-alpha;\">\n<li>O subgrupo n\u00e3o pode ser o mesmo que a op\u00e7\u00e3o que voc\u00ea j\u00e1 escolheu para &#8220;agrupar por&#8221;. Se necess\u00e1rio, voc\u00ea pode desselecionar a op\u00e7\u00e3o atual de &#8220;agrupar por&#8221; para torn\u00e1-lo dispon\u00edvel para sele\u00e7\u00e3o.<b><\/b><\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p class=\"no-margin\">Al\u00e9m disso, voc\u00ea pode filtrar por locais, membros\/grupos, hor\u00e1rios, atividades, projetos e clientes. Esse filtro ser\u00e1 aplicado aos dados exibidos abaixo.<\/p>\n<h3 id=\"horas-rastreadas-atividades-projetos-clientes\">Horas registradas em Atividades, Projetos e Clientes<\/h3>\n<p class=\"no-margin\">Voc\u00ea pode ver um resumo das horas registradas para suas atividades, projetos e clientes no gr\u00e1fico de rosca.<\/p>\n<p class=\"no-margin\">Se precisar ver em um per\u00edodo espec\u00edfico, voc\u00ea pode ajustar o filtro de data acima para ajustar os dados no gr\u00e1fico.<\/p>\n<h3 id=\"hours-breakdown\">Detalhamento de horas<\/h3>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"size-full wp-image-164086 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/hours-breakdown-PTBR.png\" alt=\"hours breakdown\" width=\"1242\" height=\"535\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/hours-breakdown-PTBR-300x129.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/hours-breakdown-PTBR-768x331.png 768w\" sizes=\"(max-width: 1242px) 100vw, 1242px\" \/><\/div>\n<p class=\"no-margin\">Os dados na tabela resumo abaixo s\u00e3o classificados com base no que est\u00e1 agrupado e subagrupado, bem como no filtro de data.<\/p>\n<p class=\"no-margin\">As barras de progresso no n\u00edvel de subgrupo representam a <b>quantidade de horas registradas para um subgrupo<\/b>, em compara\u00e7\u00e3o com o <b>total de horas registradas no n\u00edvel do grupo principal.<\/b><\/p>\n<p class=\"no-margin\"><b><i>Adicionando valor fatur\u00e1vel para indiv\u00edduos<\/i><\/b><\/p>\n<p class=\"no-margin\">O valor fatur\u00e1vel s\u00f3 pode ser definido nos perfis individuais de cada membro. Cada indiv\u00edduo tem uma taxa de cobran\u00e7a separada.<\/p>\n<p class=\"no-margin\">Voc\u00ea pode configurar isso indo para a p\u00e1gina de perfil deles. Para isso v\u00e1 para<\/p>\n<ul>\n<li>\n<p class=\"no-margin\"><b>Pessoas<\/b> &gt; Clique em uma pessoa &gt; <b>Taxa Fatur\u00e1vel<\/b> (em &#8220;Informa\u00e7\u00f5es do funcion\u00e1rio&#8221;)<\/p>\n<\/li>\n<\/ul>\n<p class=\"no-margin\">Ao mostrar o valor fatur\u00e1vel, ele calcula a <b>taxa fatur\u00e1vel dos membros da equipe que controlaram as horas multiplicada pelo\u00a0 total de horas registradas<\/b>. N\u00e3o inclui nenhuma hora extra ou dedu\u00e7\u00f5es nos c\u00e1lculos.<\/p>\n<p class=\"no-margin\"><em>Nota:\u00a0<\/em>Se voc\u00ea precisar alterar a moeda, v\u00e1 para <b>Organiza\u00e7\u00e3o<\/b> &gt; <b>Moeda de Relat\u00f3rio.<\/b><\/p>\n<hr \/>\n<h2 id=\"exportando-relatorio-horas-registradas\" data-post-processed=\"true\">Exportando o Relat\u00f3rio de Horas Registradas<\/h2>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"size-full wp-image-164097 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-export-CSV-PTBR.png\" alt=\"tracked time report export CSV\" width=\"1111\" height=\"808\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-export-CSV-PTBR-300x218.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-export-CSV-PTBR-768x559.png 768w\" sizes=\"(max-width: 1111px) 100vw, 1111px\" \/><\/div>\n<p class=\"no-margin\">Se precisar de uma an\u00e1lise mais detalhada para o seu relat\u00f3rio, voc\u00ea pode optar por ger\u00e1-lo e export\u00e1-lo.<\/p>\n<p class=\"no-margin\">Ao exportar o arquivo CSV, voc\u00ea receber\u00e1:<\/p>\n<ul>\n<li>\n<p class=\"no-margin\">Um resumo b\u00e1sico do seu relat\u00f3rio<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Opcionalmente, uma lista de registros de hor\u00e1rio da sua equipe (Lista de registros de hor\u00e1rio)<\/p>\n<\/li>\n<\/ul>\n<p class=\"no-margin\">Ao exportar o arquivo Excel, voc\u00ea receber\u00e1:<\/p>\n<ul>\n<li>\n<p class=\"no-margin\">Um resumo mais detalhado do seu relat\u00f3rio<\/p>\n<\/li>\n<li>\n<p class=\"no-margin\">Opcionalmente, uma lista de registros de hor\u00e1rio da sua equipe (Lista de registros de hor\u00e1rio)<\/p>\n<\/li>\n<\/ul>\n<p class=\"no-margin\">Voc\u00ea ainda pode personalizar todos os seus crit\u00e9rios (formato e filtros) antes de executar a exporta\u00e7\u00e3o.<\/p>\n<p class=\"no-margin\">Leia mais sobre <a class=\"intercom-content-link\" href=\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/exportar-relatorios-horas-registradas\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">como exportar o Relat\u00f3rio de Horas Registradas<\/a>.<\/p>\n","protected":false},"author":26,"template":"","meta":{"_acf_changed":false,"footnotes":""},"collections":[],"class_list":["post-145244","help","type-help","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Analisando horas com o Relat\u00f3rio de Horas Registradas | Jibble<\/title>\n<meta name=\"description\" content=\"Saiba como os funcion\u00e1rios est\u00e3o controlando as horas em atividades, projetos e clientes com o Relat\u00f3rio de Horas Registradas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analisando horas com o Relat\u00f3rio de Horas Registradas | Jibble\" \/>\n<meta property=\"og:description\" content=\"Saiba como os funcion\u00e1rios est\u00e3o controlando as horas em atividades, projetos e clientes com o Relat\u00f3rio de Horas Registradas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas\" \/>\n<meta property=\"og:site_name\" content=\"Jibble\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T22:45:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas\",\"url\":\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas\",\"name\":\"Analisando horas com o Relat\u00f3rio de Horas Registradas | Jibble\",\"isPartOf\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png\",\"datePublished\":\"2022-11-19T08:02:51+00:00\",\"dateModified\":\"2026-03-30T22:45:36+00:00\",\"description\":\"Saiba como os funcion\u00e1rios est\u00e3o controlando as horas em atividades, projetos e clientes com o Relat\u00f3rio de Horas Registradas.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas#primaryimage\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br#website\",\"url\":\"https:\/\/www.testing.devjibble.net\/pt-br\",\"name\":\"Jibble\",\"description\":\"Meet the new standard in time tracking software\",\"publisher\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.testing.devjibble.net\/pt-br?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br#organization\",\"name\":\"Jibble\",\"url\":\"https:\/\/www.testing.devjibble.net\/pt-br\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"width\":\"923\",\"height\":\"1024\",\"caption\":\"Jibble\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/pt-br#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/jibble\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Analisando horas com o Relat\u00f3rio de Horas Registradas | Jibble","description":"Saiba como os funcion\u00e1rios est\u00e3o controlando as horas em atividades, projetos e clientes com o Relat\u00f3rio de Horas Registradas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas","og_locale":"pt_BR","og_type":"article","og_title":"Analisando horas com o Relat\u00f3rio de Horas Registradas | Jibble","og_description":"Saiba como os funcion\u00e1rios est\u00e3o controlando as horas em atividades, projetos e clientes com o Relat\u00f3rio de Horas Registradas.","og_url":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas","og_site_name":"Jibble","article_modified_time":"2026-03-30T22:45:36+00:00","og_image":[{"url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas","url":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas","name":"Analisando horas com o Relat\u00f3rio de Horas Registradas | Jibble","isPartOf":{"@id":"https:\/\/www.testing.devjibble.net\/pt-br#website"},"primaryImageOfPage":{"@id":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas#primaryimage"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas#primaryimage"},"thumbnailUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png","datePublished":"2022-11-19T08:02:51+00:00","dateModified":"2026-03-30T22:45:36+00:00","description":"Saiba como os funcion\u00e1rios est\u00e3o controlando as horas em atividades, projetos e clientes com o Relat\u00f3rio de Horas Registradas.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.testing.devjibble.net\/pt-br\/ajuda\/analisando-horas-relatorio-horas-registradas#primaryimage","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/tracked-time-report-PTBR.png"},{"@type":"WebSite","@id":"https:\/\/www.testing.devjibble.net\/pt-br#website","url":"https:\/\/www.testing.devjibble.net\/pt-br","name":"Jibble","description":"Meet the new standard in time tracking software","publisher":{"@id":"https:\/\/www.testing.devjibble.net\/pt-br#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.testing.devjibble.net\/pt-br?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.testing.devjibble.net\/pt-br#organization","name":"Jibble","url":"https:\/\/www.testing.devjibble.net\/pt-br","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.testing.devjibble.net\/pt-br#\/schema\/logo\/image\/","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","width":"923","height":"1024","caption":"Jibble"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/pt-br#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jibble\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/help\/145244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/types\/help"}],"author":[{"embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/users\/26"}],"version-history":[{"count":3,"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/help\/145244\/revisions"}],"predecessor-version":[{"id":392343,"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/help\/145244\/revisions\/392343"}],"wp:attachment":[{"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/media?parent=145244"}],"wp:term":[{"taxonomy":"collections","embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/pt-br\/wp-json\/wp\/v2\/collections?post=145244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}