{"id":156369,"date":"2023-07-03T03:07:11","date_gmt":"2023-07-03T02:07:11","guid":{"rendered":"https:\/\/www.testing.devjibble.net\/help\/time-off-notifications"},"modified":"2025-06-13T07:43:06","modified_gmt":"2025-06-13T06:43:06","slug":"notifiche-del-tempo-libero","status":"publish","type":"help","link":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero","title":{"rendered":"Abilitare le notifiche del tempo libero"},"content":{"rendered":"<p>Oltre a richiedere e gestire il tempo libero per te e per i membri del tuo team, gli utenti di tutti i ruoli possono ora ricevere notifiche push e via e-mail relative al tempo libero con il <a href=\"https:\/\/www.testing.devjibble.net\/it\/software-di-monitoraggio-del-tempo-libero\">rilevatore di tempo libero dei dipendenti<\/a> di Jibble.<\/p>\n<p><strong>Questo articolo comprende:<\/strong><b><\/b><\/p>\n<ul>\n<li aria-level=\"1\"><a href=\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#tipologie-notifiche-tempo-libero\">Tipologie di notifiche sul tempo libero<\/a><\/li>\n<li aria-level=\"1\"><a href=\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#abilitare-notifiche-tempo-libero\">Abilitare le notifiche sul tempo libero<\/a><\/li>\n<\/ul>\n<hr \/>\n<h3 id=\"tipologie-notifiche-tempo-libero\"><b>Tipologie di notifiche sul tempo libero<\/b><\/h3>\n<p>Le tipologie di notifiche sul tempo libero che un utente pu\u00f2 ricevere dipendono dal suo ruolo su Jibble. Per una panoramica dei diversi tipi di notifiche sul tempo libero, consulta la tabella qui sotto:<\/p>\n<table>\n<tbody>\n<tr>\n<td><b>Ruolo<\/b><\/td>\n<td><b>Notifiche Tempo Libero<\/b><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Titolari\/amministratori\/manager<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Titolari\/amministratori\/manager potranno ricevere una notifica quando:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">I membri del team richiedono del tempo libero<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">I membri del team annullano una richiesta di tempo libero in attesa<\/span><\/li>\n<\/ul>\n<p>I titolari e gli amministratori potranno ricevere una notifica per tutti i membri dell&#8217;organizzazione, mentre i manager riceveranno solo le notifiche per i membri che gestiscono.<\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Membri<\/span><\/td>\n<td><span style=\"font-weight: 400;\">I membri potranno ricevere una notifica quando:<\/span><\/p>\n<ul>\n<li>Il tempo libero viene aggiunto per loro conto<\/li>\n<li>La loro richiesta di tempo libero in attesa viene approvata<\/li>\n<li>La loro richiesta di tempo libero in attesa viene rifiutata<\/li>\n<li>La loro richiesta di tempo libero in attesa viene modificata<\/li>\n<li>La propria richiesta di tempo libero approvata viene annullata<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h3 id=\"abilitare-notifiche-tempo-libero\"><b>Abilitare le notifiche sul tempo libero<\/b><\/h3>\n<p>Le notifiche sul tempo libero possono essere ricevute tramite e-mail e notifiche push dagli utenti di tutti i ruoli. A seconda del tuo ruolo su Jibble, potresti vedere opzioni diverse. Continua a leggere per saperne di pi\u00f9 sulle impostazioni applicabili a ciascun ruolo.<\/p>\n<p><span style=\"text-decoration: underline;\"><i><span style=\"font-weight: 400;\">Abilitare le notifiche e-mail:<\/span><\/i><\/span><\/p>\n<ol>\n<li>Per abilitare le notifiche sul tempo libero via e-mail, accedi al tuo account Jibble tramite l&#8217;app web sul desktop o sul laptop.<\/li>\n<li>Clicca sul tuo nome nell&#8217;angolo in basso a sinistra e premi su <b>Impostazioni del tuo account<\/b>.<br \/>\n<span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"size-large wp-image-199758 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png\" alt=\"account settings\" width=\"768\" height=\"419\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-300x164.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2.png 1479w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/><\/span><\/li>\n<li>Scorri in basso fino alla sezione <b>Notifiche<\/b> e clicca sull&#8217;icona a forma di matita.<br \/>\n<span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"size-large wp-image-199759 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-81-1-768x419.png\" alt=\"account settings notifications\" width=\"768\" height=\"419\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-81-1-768x419.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-81-1-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-81-1-300x164.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-81-1.png 1480w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/><\/span><\/li>\n<li>Nella sezione<b> Promemoria e Avvisi<\/b>, seleziona la casella di controllo per le <strong>R<\/strong><b>ichieste di tempo libero<\/b>.<br \/>\n<b><b><i><img decoding=\"async\" class=\"size-large wp-image-199760 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-80-2-768x418.png\" alt=\"Time off requests notifications\" width=\"768\" height=\"418\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-80-2-768x418.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-80-2-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-80-2-300x163.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-80-2.png 1480w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/>Nota: <\/i><\/b><\/b><i>Assicurati di selezionare l&#8217;icona della busta nella sezione &#8220;Avvisami tramite&#8230;&#8221;.<\/i><\/li>\n<li>I ruoli di manager vedranno due impostazioni: <b>Le mie richieste di tempo libero<\/b> e <b>Le richieste di tempo libero dei membri gestiti<\/b>.<br \/>\n<img decoding=\"async\" class=\"size-large wp-image-199761 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-84-1-768x418.png\" alt=\"Time off requests manager notifications\" width=\"768\" height=\"418\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-84-1-768x418.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-84-1-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-84-1-300x163.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-84-1.png 1480w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/><\/li>\n<li><b>Le mie richieste di tempo libero<\/b> possono essere abilitate per ricevere notifiche relative alle azioni effettuate sulle proprie richieste di tempo libero.<\/li>\n<li>Le <b>richieste di tempo libero dei membri gestiti<\/b> possono essere abilitate per ricevere notifiche quando un membro gestito richiede del tempo libero o cambia le sue richieste.<\/li>\n<li>Per i ruoli di membro, \u00e8 applicabile solo l&#8217;impostazione <b>Le mie richieste di tempo libero<\/b>.<br \/>\n<span style=\"font-weight: 400;\"><img decoding=\"async\" class=\"size-large wp-image-199762 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-83-1-768x418.png\" alt=\"Time off requests member notifications\" width=\"768\" height=\"418\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-83-1-768x418.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-83-1-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-83-1-300x163.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-83-1.png 1482w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">I ruoli di titolare e amministratore potranno scegliere se ricevere le notifiche per tutti i membri dell&#8217;organizzazione o solo per i membri gestiti, cliccando sulla freccia.<br \/>\n<b><img decoding=\"async\" class=\"size-large wp-image-199763 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Screenshot-2024-10-30-at-11.53.40\u202fAM-1-768x418.png\" alt=\"Time off requests admin notifications\" width=\"768\" height=\"418\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Screenshot-2024-10-30-at-11.53.40\u202fAM-1-768x418.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Screenshot-2024-10-30-at-11.53.40\u202fAM-1-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Screenshot-2024-10-30-at-11.53.40\u202fAM-1-300x163.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Screenshot-2024-10-30-at-11.53.40\u202fAM-1.png 1480w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/><\/b><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Clicca su<\/span><b> Salva<\/b><span style=\"font-weight: 400;\">.<img decoding=\"async\" class=\"size-large wp-image-199764 aligncenter\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-79-1-768x418.png\" alt=\"Time off requests notifications\" width=\"768\" height=\"418\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-79-1-768x418.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-79-1-160x87.png 160w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-79-1-300x163.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-79-1.png 1480w\" sizes=\"(max-width: 768px) 100vw, 540px\" \/><\/span><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><i><span style=\"font-weight: 400;\">Abilitare le notifiche push:<\/span><\/i><\/span><\/p>\n<p>Puoi abilitare le notifiche push sul tuo dispositivo mobile tramite il sistema operativo del dispositivo. Per saperne di pi\u00f9, dai un&#8217;occhiata a <a href=\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/abilitare-le-notifiche-push\">abilitare le notifiche push<\/a>.<\/p>\n<p><b>iOS<\/b><\/p>\n<ol>\n<li>Apri l&#8217;app <strong>Impostazioni<\/strong> del telefono.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Premi su <strong>Notifiche<\/strong>.<\/span><\/li>\n<li>Cerca <strong>Jibble<\/strong> nell&#8217;elenco delle app.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Premi su <strong>Jibble<\/strong>.<\/span><\/li>\n<li>Attiva la funzione &#8220;<strong>Consenti Notifiche<\/strong>&#8221; per abilitare le notifiche di Jibble.<\/li>\n<\/ol>\n<p><b>Android<\/b><\/p>\n<ol>\n<li>Apri l&#8217;app <strong>Impostazioni<\/strong> del telefono.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Premi su<strong style=\"font-weight: 400;\"> Apps<\/strong>.<\/span><\/li>\n<li>Cerca <strong>Jibble<\/strong> nell&#8217;elenco delle app.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Premi su <strong>Jibble<\/strong>.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Clicca su <strong>Notifiche<\/strong>.<\/span><\/li>\n<li>Attiva la funzione &#8220;<strong>Consenti Notifiche<\/strong>&#8221; per abilitare le notifiche di Jibble.<\/li>\n<\/ol>\n<p><b><i>Nota: <\/i><\/b><i>Le notifiche push possono essere disattivate in qualsiasi momento disabilitando la funzione per le notifiche nelle Impostazioni del dispositivo mobile.<\/i><\/p>\n","protected":false},"author":56,"template":"","meta":{"_acf_changed":false,"footnotes":""},"collections":[775],"class_list":["post-156369","help","type-help","status-publish","hentry","collections-gestione-di-ferie-e-permessi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Abilitare le notifiche del tempo libero<\/title>\n<meta name=\"description\" content=\"Resta aggiornato con notifiche in tempo reale quando una richiesta di ferie viene inoltrata, modificata, approvata, rifiutata o annullata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abilitare le notifiche del tempo libero\" \/>\n<meta property=\"og:description\" content=\"Resta aggiornato con notifiche in tempo reale quando una richiesta di ferie viene inoltrata, modificata, approvata, rifiutata o annullata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero\" \/>\n<meta property=\"og:site_name\" content=\"Jibble\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T06:43:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero\",\"url\":\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero\",\"name\":\"Abilitare le notifiche del tempo libero\",\"isPartOf\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png\",\"datePublished\":\"2023-07-03T02:07:11+00:00\",\"dateModified\":\"2025-06-13T06:43:06+00:00\",\"description\":\"Resta aggiornato con notifiche in tempo reale quando una richiesta di ferie viene inoltrata, modificata, approvata, rifiutata o annullata.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#primaryimage\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.testing.devjibble.net\/it#website\",\"url\":\"https:\/\/www.testing.devjibble.net\/it\",\"name\":\"Jibble\",\"description\":\"Meet the new standard in time tracking software\",\"publisher\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/it#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.testing.devjibble.net\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.testing.devjibble.net\/it#organization\",\"name\":\"Jibble\",\"url\":\"https:\/\/www.testing.devjibble.net\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.testing.devjibble.net\/it#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"width\":\"923\",\"height\":\"1024\",\"caption\":\"Jibble\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/it#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/jibble\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Abilitare le notifiche del tempo libero","description":"Resta aggiornato con notifiche in tempo reale quando una richiesta di ferie viene inoltrata, modificata, approvata, rifiutata o annullata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero","og_locale":"it_IT","og_type":"article","og_title":"Abilitare le notifiche del tempo libero","og_description":"Resta aggiornato con notifiche in tempo reale quando una richiesta di ferie viene inoltrata, modificata, approvata, rifiutata o annullata.","og_url":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero","og_site_name":"Jibble","article_modified_time":"2025-06-13T06:43:06+00:00","og_image":[{"url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero","url":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero","name":"Abilitare le notifiche del tempo libero","isPartOf":{"@id":"https:\/\/www.testing.devjibble.net\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#primaryimage"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#primaryimage"},"thumbnailUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png","datePublished":"2023-07-03T02:07:11+00:00","dateModified":"2025-06-13T06:43:06+00:00","description":"Resta aggiornato con notifiche in tempo reale quando una richiesta di ferie viene inoltrata, modificata, approvata, rifiutata o annullata.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.testing.devjibble.net\/it\/assistenza\/notifiche-del-tempo-libero#primaryimage","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2023\/07\/Group-82-2-768x419.png"},{"@type":"WebSite","@id":"https:\/\/www.testing.devjibble.net\/it#website","url":"https:\/\/www.testing.devjibble.net\/it","name":"Jibble","description":"Meet the new standard in time tracking software","publisher":{"@id":"https:\/\/www.testing.devjibble.net\/it#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.testing.devjibble.net\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.testing.devjibble.net\/it#organization","name":"Jibble","url":"https:\/\/www.testing.devjibble.net\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.testing.devjibble.net\/it#\/schema\/logo\/image\/","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","width":"923","height":"1024","caption":"Jibble"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/it#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jibble\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/help\/156369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/types\/help"}],"author":[{"embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/users\/56"}],"version-history":[{"count":3,"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/help\/156369\/revisions"}],"predecessor-version":[{"id":284048,"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/help\/156369\/revisions\/284048"}],"wp:attachment":[{"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/media?parent=156369"}],"wp:term":[{"taxonomy":"collections","embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/it\/wp-json\/wp\/v2\/collections?post=156369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}