{"id":339238,"date":"2025-09-08T14:23:02","date_gmt":"2025-09-08T13:23:02","guid":{"rendered":"https:\/\/www.testing.devjibble.net\/?page_id=339238"},"modified":"2026-01-14T08:02:40","modified_gmt":"2026-01-14T08:02:40","slug":"control-horario-sector-logistica","status":"publish","type":"page","link":"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica","title":{"rendered":"Control horario para el sector de la log\u00edstica 100% GRATUITO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":51,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-feature-new-youtube.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-339238","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Control horario para el sector de la log\u00edstica 100% GRATUITO<\/title>\n<meta name=\"description\" content=\"Optimiza la gesti\u00f3n log\u00edstica con el sistema de control horario de Jibble. F\u00e1cil de usar, eficiente y adaptado a tus necesidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Control horario para el sector de la log\u00edstica 100% GRATUITO\" \/>\n<meta property=\"og:description\" content=\"Optimiza la gesti\u00f3n log\u00edstica con el sistema de control horario de Jibble. F\u00e1cil de usar, eficiente y adaptado a tus necesidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica\" \/>\n<meta property=\"og:site_name\" content=\"Jibble\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-14T08:02:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica\",\"url\":\"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica\",\"name\":\"Control horario para el sector de la log\u00edstica 100% GRATUITO\",\"isPartOf\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es#website\"},\"datePublished\":\"2025-09-08T13:23:02+00:00\",\"dateModified\":\"2026-01-14T08:02:40+00:00\",\"description\":\"Optimiza la gesti\u00f3n log\u00edstica con el sistema de control horario de Jibble. F\u00e1cil de usar, eficiente y adaptado a tus necesidades.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es#website\",\"url\":\"https:\/\/www.testing.devjibble.net\/es\",\"name\":\"Jibble\",\"description\":\"Meet the new standard in time tracking software\",\"publisher\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.testing.devjibble.net\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es#organization\",\"name\":\"Jibble\",\"url\":\"https:\/\/www.testing.devjibble.net\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"width\":\"923\",\"height\":\"1024\",\"caption\":\"Jibble\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/jibble\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Control horario para el sector de la log\u00edstica 100% GRATUITO","description":"Optimiza la gesti\u00f3n log\u00edstica con el sistema de control horario de Jibble. F\u00e1cil de usar, eficiente y adaptado a tus necesidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica","og_locale":"es_ES","og_type":"article","og_title":"Control horario para el sector de la log\u00edstica 100% GRATUITO","og_description":"Optimiza la gesti\u00f3n log\u00edstica con el sistema de control horario de Jibble. F\u00e1cil de usar, eficiente y adaptado a tus necesidades.","og_url":"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica","og_site_name":"Jibble","article_modified_time":"2026-01-14T08:02:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica","url":"https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica","name":"Control horario para el sector de la log\u00edstica 100% GRATUITO","isPartOf":{"@id":"https:\/\/www.testing.devjibble.net\/es#website"},"datePublished":"2025-09-08T13:23:02+00:00","dateModified":"2026-01-14T08:02:40+00:00","description":"Optimiza la gesti\u00f3n log\u00edstica con el sistema de control horario de Jibble. F\u00e1cil de usar, eficiente y adaptado a tus necesidades.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.testing.devjibble.net\/es\/control-horario-sector-logistica"]}]},{"@type":"WebSite","@id":"https:\/\/www.testing.devjibble.net\/es#website","url":"https:\/\/www.testing.devjibble.net\/es","name":"Jibble","description":"Meet the new standard in time tracking software","publisher":{"@id":"https:\/\/www.testing.devjibble.net\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.testing.devjibble.net\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.testing.devjibble.net\/es#organization","name":"Jibble","url":"https:\/\/www.testing.devjibble.net\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","width":"923","height":"1024","caption":"Jibble"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jibble\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/pages\/339238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/comments?post=339238"}],"version-history":[{"count":3,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/pages\/339238\/revisions"}],"predecessor-version":[{"id":371117,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/pages\/339238\/revisions\/371117"}],"wp:attachment":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/media?parent=339238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}