{"id":64154,"date":"2022-11-19T08:02:46","date_gmt":"2022-11-19T08:02:46","guid":{"rendered":"https:\/\/www.testing.devjibble.net\/help\/managing-your-team-on-the-dashboard"},"modified":"2025-03-12T15:52:27","modified_gmt":"2025-03-12T15:52:27","slug":"gestionar-tu-equipo-en-el-panel-de-control","status":"publish","type":"help","link":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control","title":{"rendered":"Gestionar tu equipo desde el panel de control"},"content":{"rendered":"<p class=\"no-margin\">Tu panel de control de Jibble es el lugar donde puedes visualizar las horas registradas por tu equipo, qui\u00e9n ha entrado y qui\u00e9n ha salido, etc. en el d\u00eda, la semana o el mes.<\/p>\n<p>Para m\u00e1s detalles, consulta <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/como-funcionan-las-hojas-de-horas\">c\u00f3mo funcionan las hojas de horas<\/a> o c\u00f3mo<a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/analizar-horas-con-el-informe-de-tiempo-registrado\"> analizar las horas con el informe de horas registradas<\/a>.<\/p>\n<p class=\"no-margin\">Este art\u00edculo cubre:<\/p>\n<ul>\n<li>\n<p class=\"no-margin\"><a class=\"intercom-content-link\" href=\"#resumen-panel-control\" target=\"_self\" rel=\"nofollow noopener noreferrer\">Resumen del panel de control<\/a><\/p>\n<\/li>\n<li>\n<p class=\"no-margin\"><a class=\"intercom-content-link\" href=\"#graficos-panel-control\" target=\"_self\" rel=\"nofollow noopener noreferrer\">Gr\u00e1ficos del panel de control<\/a><\/p>\n<\/li>\n<li>\n<p class=\"no-margin\"><a class=\"intercom-content-link\" href=\"#quien-dentro-fuera\" target=\"_self\" rel=\"nofollow noopener noreferrer\">Qui\u00e9n esta dentro\/fuera<\/a><\/p>\n<\/li>\n<li>\n<p class=\"no-margin\"><a class=\"intercom-content-link\" href=\"#filtro-panel-control\" target=\"_self\" rel=\"nofollow noopener noreferrer\">\u00bfQu\u00e9 de puede filtrar en el panel de control?<\/a><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h2 id=\"resumen-panel-control\" data-post-processed=\"true\">Resumen del panel de control<\/h2>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-109958\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png\" alt=\"Resumen del panel de control\" width=\"3878\" height=\"1760\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png 3878w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325-300x136.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325-768x349.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325-1536x697.png 1536w\" sizes=\"(max-width: 3878px) 100vw, 3878px\" \/><\/div>\n<p class=\"no-margin\">El panel de control consta de varios componentes principales, entre ellos:<\/p>\n<ol>\n<li>Filtros<\/li>\n<li>Pr\u00f3ximas vacaciones<\/li>\n<li>Gr\u00e1ficos y widgets del panel de control<\/li>\n<li>Widget de qui\u00e9n est\u00e1 dentro\/fuera<\/li>\n<\/ol>\n<p class=\"no-margin\">Dependiendo de tu rol, el panel de control puede ser ligeramente diferente. Los propietarios, gerentes y administradores ver\u00e1n todo su equipo, mientras que los miembros normales solo podr\u00e1n ver sus propias horas.<\/p>\n<hr \/>\n<h2 id=\"graficos-panel-control\" data-post-processed=\"true\">Gr\u00e1ficos \/ widgets del panel de control<\/h2>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-109966\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-326.png\" alt=\"Gr\u00e1ficos \/ widgets del panel de control\" width=\"3876\" height=\"1776\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-326.png 3876w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-326-300x137.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-326-768x352.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-326-1536x704.png 1536w\" sizes=\"(max-width: 3876px) 100vw, 3876px\" \/><\/div>\n<p>Tendr\u00e1s la opci\u00f3n de personalizar los widgets seg\u00fan tus preferencias, lo que te permitir\u00e1 activarlos o desactivarlos en funci\u00f3n de tus necesidades o preferencias para tu panel de control.<\/p>\n<p>Solo tienes que hacer clic en \u00abConfigurar widgets\u00bb, situado en la parte inferior de la p\u00e1gina del panel de control, para realizar estos ajustes.<\/p>\n<h3 id=\"upcoming-holidays\" data-post-processed=\"true\">Pr\u00f3ximas vacaciones<\/h3>\n<p>Encontrar\u00e1s el widget <strong>Pr\u00f3ximas vacaciones y tiempo libre<\/strong> en la parte superior del <strong>panel de control<\/strong>. El widget enumera las tres pr\u00f3ximas vacaciones o tiempo libre de tu equipo. Puedes ampliar esta lista para ver todas las pr\u00f3ximas vacaciones.<\/p>\n<p>Lee m\u00e1s sobre <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/como-ver-festivos-dias-libres\">c\u00f3mo ver las pr\u00f3ximas vacaciones y d\u00edas libres<\/a> en tu panel de control.<\/p>\n<h3 id=\"tracked-hours\" data-post-processed=\"true\">Horas registradas<\/h3>\n<p>Las horas de este gr\u00e1fico son <em>horas registradas<\/em>, por lo que no incluye las horas de n\u00f3mina introducidas manualmente. Pero s\u00ed incluye las entradas de tiempo a\u00f1adidas manualmente.<\/p>\n<p>Las horas trabajadas son las horas del d\u00eda que se trabajan. Las horas extras est\u00e1n configuradas en tu <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-horarios-de-trabajo\">horario de trabajo<\/a> (si las horas de trabajo registradas exceden las horas de trabajo programadas, deber\u00edan considerarse horas extras, dependiendo de c\u00f3mo est\u00e9n configuradas las horas extras). Si las horas extras no est\u00e1n configuradas, las horas registradas ser\u00e1n las horas normales de trabajo.<\/p>\n<p>Las horas de descanso son las horas tomadas durante tu descanso.<\/p>\n<p class=\"no-margin\">Lee m\u00e1s sobre la <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/diferencia-entre-horas-registradas-y-horas-de-nomina\">diferencia entre las horas registradas y las horas de n\u00f3mina<\/a>.<\/p>\n<h3 id=\"activities\" data-post-processed=\"true\">Actividades<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-109974\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-327.png\" alt=\"Actividades\" width=\"2754\" height=\"922\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-327.png 2754w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-327-300x100.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-327-768x257.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-327-1536x514.png 1536w\" sizes=\"(max-width: 2754px) 100vw, 2754px\" \/><\/p>\n<p>Aqu\u00ed puede ver las 10 principales actividades de tu equipo. Pasa el rat\u00f3n por encima del gr\u00e1fico (o haz clic si est\u00e1s en el m\u00f3vil) para ver las horas registradas por actividad.<\/p>\n<p>Para configurar actividades, ve a Configuraci\u00f3n de actividades. Lee m\u00e1s sobre <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/configurar-actividades\">c\u00f3mo configurar actividades<\/a>.<\/p>\n<h3>Proyectos<img decoding=\"async\" class=\"aligncenter size-full wp-image-109982\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-328.png\" alt=\"Proyectos\" width=\"2780\" height=\"918\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-328.png 2780w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-328-300x99.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-328-768x254.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-328-1536x507.png 1536w\" sizes=\"(max-width: 2780px) 100vw, 2780px\" \/><\/h3>\n<p>Los proyectos est\u00e1n disponibles en el plan Ultimate. Podr\u00e1s ver los 10 proyectos principales de tu equipo y sus respectivas asignaciones totales de tiempo. Pasa el rat\u00f3n por encima del gr\u00e1fico (o haz clic si est\u00e1s en el m\u00f3vil) para ver las horas registradas por proyecto.<\/p>\n<p>Lee m\u00e1s sobre la <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/configurar-proyectos-y-clientes\">configuraci\u00f3n de proyectos<\/a>.<\/p>\n<h3 id=\"locations-map\" data-post-processed=\"true\">Mapa de localizaciones<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-109990\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-329.png\" alt=\"Mapa de localizaciones\" width=\"2758\" height=\"968\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-329.png 2758w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-329-300x105.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-329-768x270.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-329-1536x539.png 1536w\" sizes=\"(max-width: 2758px) 100vw, 2758px\" \/><\/p>\n<p>En este mapa, podr\u00e1s ver las ubicaciones que has creado y el n\u00famero de personas que han fichado en ellas en un radio verde.<\/p>\n<p>Si no hay nadie fichado en la ubicaci\u00f3n, el radio se mostrar\u00e1 en gris.<\/p>\n<p>Para configurar localizaciones, vaya a Configuraci\u00f3n de localizaciones. M\u00e1s informaci\u00f3n sobre la <a href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-localizaciones-y-geovallas\">configuraci\u00f3n y gesti\u00f3n de ubicaciones<\/a>.<\/p>\n<hr \/>\n<h2 id=\"quien-dentro-fuera\" data-post-processed=\"true\">Widget de dentro\/fuera<\/h2>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"aligncenter half size-full wp-image-109998\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-330.png\" alt=\"Widget de dentro\/fuera\" width=\"712\" height=\"1760\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-330.png 712w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-330-121x300.png 121w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-330-311x768.png 311w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-330-621x1536.png 621w\" sizes=\"(max-width: 712px) 100vw, 712px\" \/><\/div>\n<p>El widget de dentro\/fuera aparece en la parte derecha del panel de control.<\/p>\n<p>En este widget, puedes ver qui\u00e9n de tu equipo ha fichado, est\u00e1 en un descanso o ha salido. Si haces clic en uno de los miembros de tu equipo, acceder\u00e1s directamente a su hoja de horas personal detallada para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>La vista del panel se basa en tu propia zona horaria local, pero puedes identificar f\u00e1cilmente la zona horaria de alguien que trabaje desde una ubicaci\u00f3n diferente en el widget de dentro\/fuera.<\/p>\n<p class=\"no-margin\"><b>Por ejemplo:<\/b><\/p>\n<p>Allen Page fich\u00f3 desde el Reino Unido a las 9 de la ma\u00f1ana GMT+0. En Singapur, esta hora ser\u00eda las 5 de la tarde GMT+8.<\/p>\n<p>Como propietario, estoy en Singapur. Ver\u00e9 que la hora de entrada de Allen aparece como 5 pm GMT+0 en mi lado.<\/p>\n<hr \/>\n<h2 id=\"filtro-panel-control\" data-post-processed=\"true\">Qu\u00e9 se puede filtrar en el panel de control<\/h2>\n<div class=\"intercom-container\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-110006\" src=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-331.png\" alt=\"Qu\u00e9 se puede filtrar en el panel de control\" width=\"3878\" height=\"276\" srcset=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-331.png 3878w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-331-300x21.png 300w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-331-768x55.png 768w, https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-331-1536x109.png 1536w\" sizes=\"(max-width: 3878px) 100vw, 3878px\" \/><\/div>\n<h3 id=\"day-week-month-filters\" data-post-processed=\"true\">Filtros D\u00eda \/ Semana \/ Mes<\/h3>\n<p>Los gr\u00e1ficos del panel de control pueden filtrarse por d\u00eda, semana o mes. Esto significa, por ejemplo, que si quieres ver el total de horas registradas por tu equipo durante esta semana, puedes hacerlo cambiando el filtro del d\u00eda por el filtro de la semana.<\/p>\n<p>Estos filtros no afectan a los pr\u00f3ximos d\u00edas festivos, al mapa de localizaci\u00f3n ni al widget de entrada y salida.<\/p>\n<h3 id=\"location-groups-schedules-filters\" data-post-processed=\"true\">Filtros de ubicaci\u00f3n, grupos y horarios<\/h3>\n<p>Si tienes una ubicaci\u00f3n, grupo u horario de trabajo espec\u00edfico que quieras comprobar, puedes filtrarlos f\u00e1cilmente aqu\u00ed siempre que los hayas configurado.<\/p>\n<p>Si no, por defecto, ver\u00e1s todas las localidades, grupos y horarios de trabajo.<\/p>\n<p>Estos filtros no afectan a las pr\u00f3ximas vacaciones. Los miembros normales no ven estos filtros.<\/p>\n<h3 id=\"organization-personal-filters\" data-post-processed=\"true\">Organizaci\u00f3n \/ Filtros personales<\/h3>\n<p>Si gestionas un equipo o un grupo, tu panel de control estar\u00e1 adaptado para que tengas una visi\u00f3n general de las acciones de tu equipo o grupo. Esto ocurre cuando se selecciona \u00abOrganizaci\u00f3n\u00bb, y est\u00e1 seleccionado por defecto.<\/p>\n<p>Si solo quieres ver tus propias acciones, siempre puedes cambiar a \u00abPersonal\u00bb.<\/p>\n<p>Los miembros normales s\u00f3lo pueden ver sus propios detalles en el panel.<\/p>\n","protected":false},"author":26,"template":"","meta":{"_acf_changed":false,"footnotes":""},"collections":[472],"class_list":["post-64154","help","type-help","status-publish","hentry","collections-gestionar-personas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gestionar tu equipo en el panel de control<\/title>\n<meta name=\"description\" content=\"Utiliza el panel de control de Jibble para gestionar tu equipo y consultar las horas registradas, las vacaciones, las ubicaciones y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestionar tu equipo en el panel de control\" \/>\n<meta property=\"og:description\" content=\"Utiliza el panel de control de Jibble para gestionar tu equipo y consultar las horas registradas, las vacaciones, las ubicaciones y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control\" \/>\n<meta property=\"og:site_name\" content=\"Jibble\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T15:52:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control\",\"url\":\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control\",\"name\":\"Gestionar tu equipo en el panel de control\",\"isPartOf\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png\",\"datePublished\":\"2022-11-19T08:02:46+00:00\",\"dateModified\":\"2025-03-12T15:52:27+00:00\",\"description\":\"Utiliza el panel de control de Jibble para gestionar tu equipo y consultar las horas registradas, las vacaciones, las ubicaciones y m\u00e1s.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control#primaryimage\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es#website\",\"url\":\"https:\/\/www.testing.devjibble.net\/es\",\"name\":\"Jibble\",\"description\":\"Meet the new standard in time tracking software\",\"publisher\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.testing.devjibble.net\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es#organization\",\"name\":\"Jibble\",\"url\":\"https:\/\/www.testing.devjibble.net\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"contentUrl\":\"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png\",\"width\":\"923\",\"height\":\"1024\",\"caption\":\"Jibble\"},\"image\":{\"@id\":\"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/jibble\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gestionar tu equipo en el panel de control","description":"Utiliza el panel de control de Jibble para gestionar tu equipo y consultar las horas registradas, las vacaciones, las ubicaciones y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control","og_locale":"es_ES","og_type":"article","og_title":"Gestionar tu equipo en el panel de control","og_description":"Utiliza el panel de control de Jibble para gestionar tu equipo y consultar las horas registradas, las vacaciones, las ubicaciones y m\u00e1s.","og_url":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control","og_site_name":"Jibble","article_modified_time":"2025-03-12T15:52:27+00:00","og_image":[{"url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control","url":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control","name":"Gestionar tu equipo en el panel de control","isPartOf":{"@id":"https:\/\/www.testing.devjibble.net\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control#primaryimage"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control#primaryimage"},"thumbnailUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png","datePublished":"2022-11-19T08:02:46+00:00","dateModified":"2025-03-12T15:52:27+00:00","description":"Utiliza el panel de control de Jibble para gestionar tu equipo y consultar las horas registradas, las vacaciones, las ubicaciones y m\u00e1s.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.testing.devjibble.net\/es\/ayuda\/gestionar-tu-equipo-en-el-panel-de-control#primaryimage","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/11\/image-325.png"},{"@type":"WebSite","@id":"https:\/\/www.testing.devjibble.net\/es#website","url":"https:\/\/www.testing.devjibble.net\/es","name":"Jibble","description":"Meet the new standard in time tracking software","publisher":{"@id":"https:\/\/www.testing.devjibble.net\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.testing.devjibble.net\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.testing.devjibble.net\/es#organization","name":"Jibble","url":"https:\/\/www.testing.devjibble.net\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/","url":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","contentUrl":"https:\/\/www.testing.devjibble.net\/wp-content\/uploads\/2022\/05\/Original-copy-923x1024.png","width":"923","height":"1024","caption":"Jibble"},"image":{"@id":"https:\/\/www.testing.devjibble.net\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/jibble\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/help\/64154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/types\/help"}],"author":[{"embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/users\/26"}],"version-history":[{"count":3,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/help\/64154\/revisions"}],"predecessor-version":[{"id":244082,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/help\/64154\/revisions\/244082"}],"wp:attachment":[{"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/media?parent=64154"}],"wp:term":[{"taxonomy":"collections","embeddable":true,"href":"https:\/\/www.testing.devjibble.net\/es\/wp-json\/wp\/v2\/collections?post=64154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}